{"id":156047,"date":"2025-05-27T21:10:06","date_gmt":"2025-05-27T19:10:06","guid":{"rendered":"https:\/\/www.anteasroma.it\/new\/?post_type=portfolio&#038;p=156047"},"modified":"2025-06-06T20:55:26","modified_gmt":"2025-06-06T18:55:26","slug":"portierato-sociale","status":"publish","type":"portfolio","link":"https:\/\/www.anteasroma.it\/new\/progetti\/portierato-sociale\/","title":{"rendered":"Portierato Sociale presso &#8220;La casa dei servizi&#8221;"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;5&#8243; bottom_padding=&#8221;5&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; uncode_shortcode_id=&#8221;364759&#8243;][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;4&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; align_mobile=&#8221;align_center_mobile&#8221; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243; uncode_shortcode_id=&#8221;112557&#8243;][vc_custom_heading text_font=&#8221;font-169484&#8243; css_animation=&#8221;curtain-words&#8221; animation_speed=&#8221;600&#8243; uncode_shortcode_id=&#8221;132290&#8243;]Un presidio di prossimit\u00e0 per una comunit\u00e0 pi\u00f9 solidale[\/vc_custom_heading][vc_row_inner row_inner_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;4&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; uncode_shortcode_id=&#8221;632177&#8243; limit_content=&#8221;&#8221;][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243; uncode_shortcode_id=&#8221;146423&#8243;][vc_column_text uncode_shortcode_id=&#8221;122272&#8243;]Anteas Roma \u00e8 presente all\u2019interno della Casa dei Servizi di Cesano, nel Municipio Roma XV, con un ruolo attivo e continuativo. In questo spazio accogliente, inclusivo e aperto a tutte e tutti, l\u2019associazione gestisce e finanzia interamente il Portierato Sociale, un presidio stabile nato per rispondere concretamente ai bisogni del territorio.<br \/>\nIl Portierato \u00e8 un luogo di ascolto, orientamento, accompagnamento e socializzazione, dedicato in particolare alle persone pi\u00f9 fragili. Ogni giorno, le volontarie e i volontari di Anteas Roma offrono supporto, informazioni e vicinanza, costruendo relazioni di fiducia e promuovendo l\u2019inclusione.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243; uncode_shortcode_id=&#8221;453961&#8243;][vc_column_text uncode_shortcode_id=&#8221;118987&#8243;]Questo intervento, completamente sostenuto da Anteas Roma, rappresenta un impegno concreto per portare umanit\u00e0 nei servizi e rafforzare i legami sociali nei quartieri.<\/p>\n<p><strong>Il progetto nasce dalla collaborazione con Roma Capitale, il Municipio XV e diversi partner, tra cui la Fondazione Mondo Digitale, che contribuisce con servizi digitali per favorire l\u2019accesso alle tecnologie.<\/strong>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8221;yes&#8221; row_height_percent=&#8221;75&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;0&#8243; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;0&#8243; shift_y=&#8221;0&#8243;][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; back_image=&#8221;156701&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;4&#8243; mobile_width=&#8221;0&#8243; zoom_width=&#8221;0&#8243; zoom_height=&#8221;0&#8243; width=&#8221;1\/2&#8243; mobile_height=&#8221;380&#8243; uncode_shortcode_id=&#8221;720899&#8243;][\/vc_column][vc_column column_width_use_pixel=&#8221;yes&#8221; position_vertical=&#8221;middle&#8221; gutter_size=&#8221;3&#8243; override_padding=&#8221;yes&#8221; column_padding=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;4&#8243; align_mobile=&#8221;align_center_mobile&#8221; mobile_width=&#8221;0&#8243; zoom_width=&#8221;0&#8243; zoom_height=&#8221;0&#8243; width=&#8221;1\/2&#8243; uncode_shortcode_id=&#8221;707498&#8243; back_color_type=&#8221;uncode-solid&#8221; back_color_solid=&#8221;#f8f8fa&#8221; column_width_pixel=&#8221;400&#8243;][vc_custom_heading heading_semantic=&#8221;h6&#8243; text_size=&#8221;h5&#8243; css_animation=&#8221;bottom-t-top&#8221; animation_delay=&#8221;400&#8243; uncode_shortcode_id=&#8221;163448&#8243;]Con il Portierato Sociale di Cesano, ANTEAS ROMA rinnova la sua missione: essere ogni giorno vicina alle persone, con gesti semplici ma profondamente trasformativi.[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8221;yes&#8221; row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;7&#8243; top_padding=&#8221;5&#8243; bottom_padding=&#8221;5&#8243; back_color=&#8221;accent&#8221; overlay_alpha=&#8221;100&#8243; gutter_size=&#8221;4&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; content_parallax=&#8221;0&#8243; style=&#8221;inherited&#8221; uncode_shortcode_id=&#8221;139195&#8243; back_color_type=&#8221;uncode-palette&#8221;][vc_column column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;4&#8243; style=&#8221;dark&#8221; font_family=&#8221;font-136269&#8243; overlay_alpha=&#8221;100&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; zoom_width=&#8221;0&#8243; zoom_height=&#8221;0&#8243; width=&#8221;1\/1&#8243; uncode_shortcode_id=&#8221;796142&#8243;][vc_custom_heading uncode_shortcode_id=&#8221;473996&#8243;]Risultati e successi[\/vc_custom_heading][vc_row_inner row_inner_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;2&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; limit_content=&#8221;&#8221; uncode_shortcode_id=&#8221;205576&#8243;][vc_column_inner column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;3&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/3&#8243; uncode_shortcode_id=&#8221;631948&#8243;][vc_single_image media=&#8221;2440&#8243; media_width_percent=&#8221;100&#8243; media_ratio=&#8221;three-four&#8221; alignment=&#8221;center&#8221; image=&#8221;2689&#8243; border_color=&#8221;grey&#8221; img_link_target=&#8221;_self&#8221; img_size=&#8221;full&#8221; uncode_shortcode_id=&#8221;131966&#8243;][vc_column_text uncode_shortcode_id=&#8221;344455&#8243;]01. Clean and minimal[\/vc_column_text][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;3&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/3&#8243; uncode_shortcode_id=&#8221;126312&#8243;][vc_single_image media=&#8221;11297&#8243; media_width_percent=&#8221;100&#8243; media_ratio=&#8221;three-four&#8221; alignment=&#8221;center&#8221; image=&#8221;2689&#8243; border_color=&#8221;grey&#8221; img_link_target=&#8221;_self&#8221; img_size=&#8221;full&#8221; uncode_shortcode_id=&#8221;125311&#8243;][vc_column_text uncode_shortcode_id=&#8221;109267&#8243;]02. Premium design[\/vc_column_text][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;3&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/3&#8243; uncode_shortcode_id=&#8221;615793&#8243;][vc_single_image media=&#8221;11296&#8243; media_width_percent=&#8221;100&#8243; media_ratio=&#8221;three-four&#8221; alignment=&#8221;center&#8221; image=&#8221;2689&#8243; border_color=&#8221;grey&#8221; img_link_target=&#8221;_self&#8221; img_size=&#8221;full&#8221; uncode_shortcode_id=&#8221;116377&#8243;][vc_column_text uncode_shortcode_id=&#8221;176532&#8243;]03. Lovely product[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8221;yes&#8221; row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;5&#8243; bottom_padding=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_use_pixel=&#8221;yes&#8221; shift_y=&#8221;0&#8243; z_index=&#8221;2&#8243; top_divider=&#8221;step&#8221; enable_bottom_divider=&#8221;default&#8221; bottom_divider=&#8221;step&#8221; shape_bottom_h_use_pixel=&#8221;true&#8221; shape_bottom_height_percent=&#8221;20&#8243; shape_bottom_opacity=&#8221;100&#8243; shape_bottom_index=&#8221;0&#8243; content_parallax=&#8221;0&#8243; el_class=&#8221;video-container&#8221; uncode_shortcode_id=&#8221;179398&#8243; column_width_pixel=&#8221;1272&#8243; back_color_type=&#8221;uncode-solid&#8221; back_color_solid=&#8221;#f8f8fa&#8221;][vc_column column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;4&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243; uncode_shortcode_id=&#8221;212754&#8243;][vc_custom_heading uncode_shortcode_id=&#8221;668036&#8243;]Guarda il video[\/vc_custom_heading][vc_row_inner limit_content=&#8221;&#8221;][vc_column_inner column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243; uncode_shortcode_id=&#8221;898364&#8243;][vc_single_image media=&#8221;11299&#8243; media_width_percent=&#8221;100&#8243; media_ratio=&#8221;sixteen-nine&#8221; shape=&#8221;img-round&#8221; radius=&#8221;xs&#8221; uncode_shortcode_id=&#8221;721532&#8243;][vc_icon display=&#8221;absolute-center&#8221; icon=&#8221;fa fa-play&#8221; background_style=&#8221;fa-rounded&#8221; size=&#8221;fa-2x&#8221; icon_automatic=&#8221;yes&#8221; shadow=&#8221;yes&#8221; media_lightbox=&#8221;72008&#8243; uncode_shortcode_id=&#8221;469471&#8243;][\/vc_icon][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Leverage agile frameworks to provide a robust synopsis for high level of overviews, iterative approaches to corporate strategy foster collaborative thinking to further the overall value proposition, at the end of the day, organically grow the world view of disruptive innovation via workplace diversity and empowerment.<\/p>\n","protected":false},"author":1,"featured_media":156043,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"portfolio_category":[70],"class_list":["post-156047","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-solidarieta"],"_links":{"self":[{"href":"https:\/\/www.anteasroma.it\/new\/wp-json\/wp\/v2\/portfolio\/156047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.anteasroma.it\/new\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.anteasroma.it\/new\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.anteasroma.it\/new\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.anteasroma.it\/new\/wp-json\/wp\/v2\/comments?post=156047"}],"version-history":[{"count":17,"href":"https:\/\/www.anteasroma.it\/new\/wp-json\/wp\/v2\/portfolio\/156047\/revisions"}],"predecessor-version":[{"id":156712,"href":"https:\/\/www.anteasroma.it\/new\/wp-json\/wp\/v2\/portfolio\/156047\/revisions\/156712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.anteasroma.it\/new\/wp-json\/wp\/v2\/media\/156043"}],"wp:attachment":[{"href":"https:\/\/www.anteasroma.it\/new\/wp-json\/wp\/v2\/media?parent=156047"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/www.anteasroma.it\/new\/wp-json\/wp\/v2\/portfolio_category?post=156047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}